{"id":13246,"date":"2021-12-28T16:09:58","date_gmt":"2021-12-28T16:09:58","guid":{"rendered":"http:\/\/pixykornerdevelopment.co.za\/afrecnews\/?p=13246"},"modified":"2021-12-30T15:01:38","modified_gmt":"2021-12-30T15:01:38","slug":"what-will-it-take-for-africa-to-reach-net-zero-emission","status":"publish","type":"post","link":"https:\/\/energy4africa.africa\/fr\/2021\/12\/28\/what-will-it-take-for-africa-to-reach-net-zero-emission\/","title":{"rendered":"Que faudra-t-il pour que l'Afrique atteigne le niveau z\u00e9ro d'\u00e9missions nettes ?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13425\" src=\"http:\/\/pixykornerdevelopment.co.za\/afrecnews\/wp-content\/uploads\/2021\/12\/emission.png\" alt=\"\" width=\"730\" height=\"455\" srcset=\"https:\/\/energy4africa.africa\/wp-content\/uploads\/2021\/12\/emission.png 730w, https:\/\/energy4africa.africa\/wp-content\/uploads\/2021\/12\/emission-300x187.png 300w, https:\/\/energy4africa.africa\/wp-content\/uploads\/2021\/12\/emission-600x374.png 600w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/p>\n<p>Alors que les effets du changement climatique continuent de s'aggraver et de constituer une s\u00e9rieuse menace pour le d\u00e9veloppement socio-\u00e9conomique de la plan\u00e8te, l'Afrique cherche des solutions pour faire progresser la situation du continent en mati\u00e8re d'adaptation au changement climatique, d'\u00e9largissement de l'acc\u00e8s \u00e0 l'\u00e9nergie moderne, de r\u00e9duction de la pauvret\u00e9 et de cr\u00e9ation d'emplois, tout en contribuant aux objectifs mondiaux visant \u00e0 contourner la contrainte du carbone dans le d\u00e9veloppement futur du continent.<\/p>\n<p>Tenu sous le th\u00e8me : \"Opportunit\u00e9s et d\u00e9fis pour la transition \u00e9nerg\u00e9tique africaine : Que faudra-t-il pour que l\u2019Afrique atteigne un niveau z\u00e9ro d'\u00e9missions nettes ? Cet \u00e9v\u00e9nement en ligne de haut niveau, organis\u00e9 par la Commission de l'Union africaine (CUA) par l'interm\u00e9diaire de la Commission africaine de l'\u00e9nergie (AFREC) pendant les r\u00e9unions de la COP26, a appel\u00e9 \u00e0 des mesures audacieuses li\u00e9es aux opportunit\u00e9s et aux d\u00e9fis auxquels l\u2019Afrique est confront\u00e9e, afin d'acc\u00e9l\u00e9rer les actions en vue de la mise en \u0153uvre compl\u00e8te de l'accord de Paris et de la convention-cadre des Nations unies sur les changements climatiques.<\/p>\n<p>Son Excellence Dr Amani Abou-Zeid, commissaire aux infrastructures et \u00e0 l'\u00e9nergie \u00e0 la Commission de l'Union africaine, a prononc\u00e9 un discours liminaire, soulignant qu'il est dans l'int\u00e9r\u00eat de l'Afrique de se joindre aux efforts mondiaux pour passer \u00e0 des \u00e9missions nettes nulles, afin d'att\u00e9nuer les impacts futurs du changement climatique sur le continent et de r\u00e9duire les co\u00fbts d'adaptation.<\/p>\n<p>''La disponibilit\u00e9 d'abondantes ressources d'\u00e9nergie renouvelable sur le continent, telles que l'hydro\u00e9lectricit\u00e9, le solaire, l'\u00e9olien, la g\u00e9othermie et la bio\u00e9nergie, peut transformer le secteur \u00e9nerg\u00e9tique africain en une \u00e9nergie moderne et durable gr\u00e2ce \u00e0 des syst\u00e8mes en r\u00e9seau et hors r\u00e9seau. Ces ressources offrent des possibilit\u00e9s d'acc\u00e9l\u00e9rer l'acc\u00e8s \u00e0 l'\u00e9nergie propre sur le continent par le biais de la transition \u00e9nerg\u00e9tique et notamment en prenant en compte le gaz naturel comme un combustible de transition \u00e9nerg\u00e9tique pour l'\u00e9lectricit\u00e9 et la cuisson propre'', a-t-elle soulign\u00e9.\nLe Dr Abou-Zeid a \u00e9galement mis en exergue que la volont\u00e9 et l'engagement politiques de l'Afrique sont tr\u00e8s importants pour acc\u00e9l\u00e9rer l'adoption des \u00e9nergies renouvelables, comme en t\u00e9moignent les objectifs des plans nationaux des pays, refl\u00e9t\u00e9s dans leurs contributions d\u00e9termin\u00e9es au niveau national (CDN), pour r\u00e9aliser les ambitions en mati\u00e8re de climat et de d\u00e9veloppement. La COP26 devrait chercher \u00e0 stimuler des actions concr\u00e8tes pour combler l'\u00e9norme d\u00e9ficit de financement afin de parvenir \u00e0 des \u00e9missions nettes nulles d'ici 2050\", a-t-elle encore soulign\u00e9.<br \/>\nDr Abou-Zeid also emphasized that Africa\u2019s political will and commitment is highly significant to accelerate the uptake of renewable energy as evidenced by the targets within countries national plans reflected in their Nationally Determined Contributions (NDCs) to achieve climate and development ambitions. \u2018\u2018COP26 should seek to stimulate concrete actions to address the huge financing gap to achieve net-zero emissions by 2050\u2019\u2019, she further stressed.<\/p>\n<p>Bien que l'Afrique contribue \u00e0 environ 3,6 % des \u00e9missions mondiales de CO2, il est \u00e9vident que les effets du changement climatique sur l'Afrique sont plus graves, sachant que l'acc\u00e8s \u00e0 une \u00e9nergie propre et abordable reste l'un des principaux d\u00e9fis auxquels le continent est confront\u00e9. Il est donc essentiel de s'attaquer aux obstacles persistants qui entravent le d\u00e9veloppement de l'\u00e9nergie sur le continent par le biais de cadres techniques, financiers, politiques, r\u00e9glementaires et de march\u00e9s.<\/p>\n<p>S.E. Dr Gerd Muller, ministre f\u00e9d\u00e9ral allemand de la coop\u00e9ration \u00e9conomique et du d\u00e9veloppement, a appel\u00e9 les nations \u00e0 unir leurs forces pour agir d\u00e8s maintenant sur les questions de changement climatique et de d\u00e9carbonisation. \"La d\u00e9carbonisation est n\u00e9cessaire car le secteur de l'\u00e9nergie est \u00e0 l'origine de plus de deux tiers de toutes les \u00e9missions de CO2\". Il a \u00e9galement exprim\u00e9 l'engagement de l'Allemagne \u00e0 collaborer avec l'Afrique dans ses ambitions en mati\u00e8re de transition \u00e9nerg\u00e9tique, saluant l'initiative UA-UE pour l'\u00e9nergie verte propos\u00e9e comme un instrument appropri\u00e9 pour faciliter une approche bicontinentale.<\/p>\n<p>H.E. M. Benatou ZIANE, Ministre de la Transition Energ\u00e9tique et des \u00c9nergies Renouvelables d'Alg\u00e9rie a not\u00e9, dans une d\u00e9claration lue en son nom par M. CHABANE Merouane, Secr\u00e9taire G\u00e9n\u00e9ral, que l'Afrique doit diversifier ses sources d'\u00e9nergie et s'affranchir de la d\u00e9pendance de l'hydro\u00e9lectricit\u00e9, afin de garantir la s\u00e9curit\u00e9 \u00e9nerg\u00e9tique des g\u00e9n\u00e9rations futures pour le d\u00e9veloppement d'une \u00e9conomie bas\u00e9e sur un mod\u00e8le align\u00e9 sur les besoins socio-\u00e9conomiques, favorisant l'\u00e9galit\u00e9, la cr\u00e9ation d'emplois et r\u00e9pondant aux d\u00e9fis \u00e9nerg\u00e9tiques de l'Afrique. \"L'Alg\u00e9rie a d\u00e9j\u00e0 commenc\u00e9 \u00e0 travailler sur un cadre politique pour un nouveau mod\u00e8le \u00e9nerg\u00e9tique, afin d'\u00e9quilibrer un mix \u00e9nerg\u00e9tique local favorable \u00e0 la transition et \u00e0 la r\u00e9duction des \u00e9missions d'ici 2030. Nous nous employons \u00e9galement \u00e0 d\u00e9velopper les \u00e9nergies renouvelables en passant \u00e0 15 GW d'ici 2035'', a-t-il soulign\u00e9.<\/p>\n<p>Au cours des d\u00e9bats, S.E. Dr Matthew Opoku Prempeh, ministre de l'\u00e9nergie du Ghana, M. Jean-Paul Adam, directeur de la technologie, du changement climatique et de la gestion des ressources naturelles \u00e0 la CEA, M. Henry Paul Batchi Baldeh, directeur du d\u00e9veloppement du syst\u00e8me \u00e9lectrique \u00e0 la BAfD, et M. Mamadou Diakhit\u00e9, chef de division par int\u00e9rim pour la durabilit\u00e9 environnementale \u00e0 l'AUDA-NEPAD, ont soulign\u00e9 qu'il est essentiel pour l'Afrique d'\u00eatre r\u00e9aliste au moment de choisir les m\u00e9thodes de transition \u00e9nerg\u00e9tique qui r\u00e9pondent \u00e0 ses besoins et circonstances sp\u00e9cifiques :<\/p>\n<ul>\n<li>Il est imp\u00e9ratif d'am\u00e9liorer les politiques, la l\u00e9gislation et les approches de mise en \u0153uvre aux niveaux national, r\u00e9gional et continental, afin de cr\u00e9er un environnement favorable au d\u00e9veloppement ;<\/li>\n<li>Se lancer dans la voie du d\u00e9veloppement vert sans ignorer les ambitions de l'Afrique en mati\u00e8re de d\u00e9veloppement des infrastructures et d'industrialisation ;<\/li>\n<li>D\u00e9velopper des projets bancables pour \u00e9largir l'acc\u00e8s aux financements et aux investissements ;<\/li>\n<li>Adopter une combinaison de solutions \u00e9nerg\u00e9tiques pour r\u00e9pondre aux besoins de chaque pays, y compris des solutions aux tarifs \u00e9lev\u00e9s et l'accessibilit\u00e9 aux options \u00e9nerg\u00e9tiques durables ;<\/li>\n<li>Promouvoir l'efficacit\u00e9 \u00e9nerg\u00e9tique qui est n\u00e9cessaire \u00e0 la transition \u00e9nerg\u00e9tique ;<\/li>\n<li>Se concentrer sur la construction d'infrastructures \u00e9nerg\u00e9tiques et le renforcement des corridors de transmission.<\/li>\n<\/ul>\n<p class=\" translation-block\">L'Union africaine, ainsi que ses diff\u00e9rentes agences sp\u00e9cialis\u00e9es et ses partenaires, ont pris des mesures concr\u00e8tes en \u00e9laborant des programmes et des projets de d\u00e9veloppement \u00e0 l'\u00e9chelle du continent, tels que l'am\u00e9lioration des infrastructures pour accro\u00eetre le r\u00e9seau \u00e9lectrique r\u00e9gional d'ici 2040. Certaines de ces initiatives comprennent le <a href=\"https:\/\/au.int\/en\/pressreleases\/20210604\/african-union-launches-worlds-largest-single-electricity-market-afsem\" target=\"_blank\" rel=\"noopener\">March\u00e9 unique de l'\u00e9lectricit\u00e9 en Afrique<\/a>, le d\u00e9veloppement du <a href=\"https:\/\/au-afrec.org\/en\/programs\/african-energy-information-system\" target=\"_blank\" rel=\"noopener\">Syst\u00e8me africain d'information sur l'\u00e9nergie<\/a>, <a href=\"https:\/\/www.au-pida.org\/\" target=\"_blank\" rel=\"noopener\">Le projet PIDA<\/a> et <a href=\"https:\/\/au.int\/ar\/node\/39532\" target=\"_blank\" rel=\"noopener\">G\u00e9othermie<\/a> parmi d'autres. D'autres \u00e9tudes sur la transition \u00e9nerg\u00e9tique dans divers domaines th\u00e9matiques tels que le p\u00e9trole et le gaz, la transition \u00e9nerg\u00e9tique, l'efficacit\u00e9 \u00e9nerg\u00e9tique, la bio\u00e9nergie et le renforcement des capacit\u00e9s sont en cours. Une fois termin\u00e9es, l'UA, et en particulier l'AFREC, sera en mesure d'\u00e9laborer un plan strat\u00e9gique de r\u00e9ponse \u00e9clair\u00e9 qui pourra stimuler et consolider le d\u00e9veloppement \u00e9nerg\u00e9tique sur le continent.<\/p>","protected":false},"excerpt":{"rendered":"<p>As impacts of climate change continue to worsen and pose significant threats to socio-economic development globally, Africa is looking at solutions which can unlock the continents position on climate adaptation, expansion to modern energy access, reduction on poverty and creating jobs, whilst contributing to the global objectives of circumventing the lock-in of carbon into future\u2026<\/p>","protected":false},"author":1,"featured_media":13247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-13246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-main-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/posts\/13246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/comments?post=13246"}],"version-history":[{"count":4,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/posts\/13246\/revisions"}],"predecessor-version":[{"id":13514,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/posts\/13246\/revisions\/13514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/media\/13247"}],"wp:attachment":[{"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/media?parent=13246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/categories?post=13246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energy4africa.africa\/fr\/wp-json\/wp\/v2\/tags?post=13246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}